{"id":20606,"date":"2016-08-04T16:52:54","date_gmt":"2016-08-04T16:52:54","guid":{"rendered":"http:\/\/micofora.com\/en\/faq-items\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/"},"modified":"2016-10-30T12:45:34","modified_gmt":"2016-10-30T12:45:34","slug":"que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia","status":"publish","type":"avada_faq","link":"https:\/\/micofora.com\/en\/faq-items\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/","title":{"rendered":"\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda?"},"content":{"rendered":"<p>Est\u00e1 ampliamente demostrado por numerosos estudios cient\u00edficos que las micorrizas ayudan a las plantas a aguantar mucho mejor las situaciones de sequ\u00eda, principalmente porque la planta aumenta su contenido en potasio. Esto lo hacen fundamentalmente a trav\u00e9s de la red que la micorriza forma en el suelo alrededor de la planta que act\u00faa como verdaderas ca\u00f1er\u00edas de agua. Por lo tanto las micorrizas est\u00e1n especialmente indicadas en situaciones de sequ\u00eda o suelos salinos y calizos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 ampliamente demostrado por numerosos estudios cient\u00edficos que las micorrizas ayudan a las plantas a aguantar mucho mejor las situaciones de sequ\u00eda, principalmente porque la planta aumenta su contenido en potasio. Esto lo hacen fundamentalmente a trav\u00e9s de la red que la micorriza forma en el suelo alrededor de la planta que act\u00faa como verdaderas  [&#8230;]<\/p>\n","protected":false},"author":6,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"faq_category":[665],"class_list":["post-20606","avada_faq","type-avada_faq","status-publish","format-standard","hentry","faq_category-micorrizas-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda? - Micofora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda? - Micofora\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 ampliamente demostrado por numerosos estudios cient\u00edficos que las micorrizas ayudan a las plantas a aguantar mucho mejor las situaciones de sequ\u00eda, principalmente porque la planta aumenta su contenido en potasio. Esto lo hacen fundamentalmente a trav\u00e9s de la red que la micorriza forma en el suelo alrededor de la planta que act\u00faa como verdaderas [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/\" \/>\n<meta property=\"og:site_name\" content=\"Micofora\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-30T12:45:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/micofora.com\\\/en\\\/avada_faq\\\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\\\/\",\"url\":\"https:\\\/\\\/micofora.com\\\/en\\\/avada_faq\\\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\\\/\",\"name\":\"\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda? - Micofora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/micofora.com\\\/#website\"},\"datePublished\":\"2016-08-04T16:52:54+00:00\",\"dateModified\":\"2016-10-30T12:45:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/micofora.com\\\/en\\\/avada_faq\\\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/micofora.com\\\/en\\\/avada_faq\\\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/micofora.com\\\/en\\\/avada_faq\\\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/micofora.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/micofora.com\\\/faq-items\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/micofora.com\\\/#website\",\"url\":\"https:\\\/\\\/micofora.com\\\/\",\"name\":\"Micofora\",\"description\":\"Micologia Forestal &amp; Aplicada\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/micofora.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda? - Micofora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda? - Micofora","og_description":"Est\u00e1 ampliamente demostrado por numerosos estudios cient\u00edficos que las micorrizas ayudan a las plantas a aguantar mucho mejor las situaciones de sequ\u00eda, principalmente porque la planta aumenta su contenido en potasio. Esto lo hacen fundamentalmente a trav\u00e9s de la red que la micorriza forma en el suelo alrededor de la planta que act\u00faa como verdaderas [...]","og_url":"https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/","og_site_name":"Micofora","article_modified_time":"2016-10-30T12:45:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/","url":"https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/","name":"\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda? - Micofora","isPartOf":{"@id":"https:\/\/micofora.com\/#website"},"datePublished":"2016-08-04T16:52:54+00:00","dateModified":"2016-10-30T12:45:34+00:00","breadcrumb":{"@id":"https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/micofora.com\/en\/avada_faq\/que-ventajas-tiene-aplicar-micorrizas-en-tiempos-de-sequia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/micofora.com\/en\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/micofora.com\/faq-items\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 ventajas tiene aplicar micorrizas en tiempos de sequ\u00eda?"}]},{"@type":"WebSite","@id":"https:\/\/micofora.com\/#website","url":"https:\/\/micofora.com\/","name":"Micofora","description":"Micologia Forestal &amp; Aplicada","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/micofora.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/micofora.com\/en\/wp-json\/wp\/v2\/avada_faq\/20606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/micofora.com\/en\/wp-json\/wp\/v2\/avada_faq"}],"about":[{"href":"https:\/\/micofora.com\/en\/wp-json\/wp\/v2\/types\/avada_faq"}],"author":[{"embeddable":true,"href":"https:\/\/micofora.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/micofora.com\/en\/wp-json\/wp\/v2\/comments?post=20606"}],"version-history":[{"count":0,"href":"https:\/\/micofora.com\/en\/wp-json\/wp\/v2\/avada_faq\/20606\/revisions"}],"wp:attachment":[{"href":"https:\/\/micofora.com\/en\/wp-json\/wp\/v2\/media?parent=20606"}],"wp:term":[{"taxonomy":"faq_category","embeddable":true,"href":"https:\/\/micofora.com\/en\/wp-json\/wp\/v2\/faq_category?post=20606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}