{"id":20632,"date":"2016-08-04T16:47:52","date_gmt":"2016-08-04T16:47:52","guid":{"rendered":"http:\/\/micofora.com\/ca\/faq-items\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/"},"modified":"2016-10-30T12:46:30","modified_gmt":"2016-10-30T12:46:30","slug":"puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas","status":"publish","type":"avada_faq","link":"https:\/\/micofora.com\/ca\/faq-items\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/","title":{"rendered":"\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS?"},"content":{"rendered":"<p>Hay ciertos productos fitosanitarios que s\u00ed son compatibles, como el Propamocarb, que incluso aumenta el efecto de la micorriza; o el fosetil-Al. Hay otros sin embargo que est\u00e1n totalmente contraindicados, como el bromuro de metilo. En general hay que respetar un \u201cplazo de seguridad\u201d de unas dos o tres semanas tras inocular micorrizas para que a \u00e9stas les de tiempo de actuar y no se afecten. Los efectos de los fungicidas que suelen aplicarse en vivero (Tachigaren, Benomilo, Captan, Tiram) no suelen tener efectos sobre ECTOPLANT, a las dosis standart.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay ciertos productos fitosanitarios que s\u00ed son compatibles, como el Propamocarb, que incluso aumenta el efecto de la micorriza; o el fosetil-Al. Hay otros sin embargo que est\u00e1n totalmente contraindicados, como el bromuro de metilo. En general hay que respetar un \u201cplazo de seguridad\u201d de unas dos o tres semanas tras inocular micorrizas para que  [&#8230;]<\/p>\n","protected":false},"author":6,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"faq_category":[667],"class_list":["post-20632","avada_faq","type-avada_faq","status-publish","format-standard","hentry","faq_category-micorrizas-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS? - Micofora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS? - Micofora\" \/>\n<meta property=\"og:description\" content=\"Hay ciertos productos fitosanitarios que s\u00ed son compatibles, como el Propamocarb, que incluso aumenta el efecto de la micorriza; o el fosetil-Al. Hay otros sin embargo que est\u00e1n totalmente contraindicados, como el bromuro de metilo. En general hay que respetar un \u201cplazo de seguridad\u201d de unas dos o tres semanas tras inocular micorrizas para que [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/\" \/>\n<meta property=\"og:site_name\" content=\"Micofora\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-30T12:46:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/micofora.com\\\/ca\\\/avada_faq\\\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\\\/\",\"url\":\"https:\\\/\\\/micofora.com\\\/ca\\\/avada_faq\\\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\\\/\",\"name\":\"\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS? - Micofora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/micofora.com\\\/#website\"},\"datePublished\":\"2016-08-04T16:47:52+00:00\",\"dateModified\":\"2016-10-30T12:46:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/micofora.com\\\/ca\\\/avada_faq\\\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/micofora.com\\\/ca\\\/avada_faq\\\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/micofora.com\\\/ca\\\/avada_faq\\\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/micofora.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/micofora.com\\\/faq-items\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/micofora.com\\\/#website\",\"url\":\"https:\\\/\\\/micofora.com\\\/\",\"name\":\"Micofora\",\"description\":\"Micologia Forestal &amp; Aplicada\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/micofora.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS? - Micofora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/","og_locale":"ca_ES","og_type":"article","og_title":"\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS? - Micofora","og_description":"Hay ciertos productos fitosanitarios que s\u00ed son compatibles, como el Propamocarb, que incluso aumenta el efecto de la micorriza; o el fosetil-Al. Hay otros sin embargo que est\u00e1n totalmente contraindicados, como el bromuro de metilo. En general hay que respetar un \u201cplazo de seguridad\u201d de unas dos o tres semanas tras inocular micorrizas para que [...]","og_url":"https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/","og_site_name":"Micofora","article_modified_time":"2016-10-30T12:46:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/","url":"https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/","name":"\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS? - Micofora","isPartOf":{"@id":"https:\/\/micofora.com\/#website"},"datePublished":"2016-08-04T16:47:52+00:00","dateModified":"2016-10-30T12:46:30+00:00","breadcrumb":{"@id":"https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/micofora.com\/ca\/avada_faq\/puedo-utilizar-fitosanitarios-convencionales-junto-con-las-micorrizas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/micofora.com\/ca\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/micofora.com\/faq-items\/"},{"@type":"ListItem","position":3,"name":"\u00bfPuedo utilizar fitosanitarios convencionales junto con las MICORRIZAS?"}]},{"@type":"WebSite","@id":"https:\/\/micofora.com\/#website","url":"https:\/\/micofora.com\/","name":"Micofora","description":"Micologia Forestal &amp; Aplicada","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/micofora.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/micofora.com\/ca\/wp-json\/wp\/v2\/avada_faq\/20632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/micofora.com\/ca\/wp-json\/wp\/v2\/avada_faq"}],"about":[{"href":"https:\/\/micofora.com\/ca\/wp-json\/wp\/v2\/types\/avada_faq"}],"author":[{"embeddable":true,"href":"https:\/\/micofora.com\/ca\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/micofora.com\/ca\/wp-json\/wp\/v2\/comments?post=20632"}],"version-history":[{"count":0,"href":"https:\/\/micofora.com\/ca\/wp-json\/wp\/v2\/avada_faq\/20632\/revisions"}],"wp:attachment":[{"href":"https:\/\/micofora.com\/ca\/wp-json\/wp\/v2\/media?parent=20632"}],"wp:term":[{"taxonomy":"faq_category","embeddable":true,"href":"https:\/\/micofora.com\/ca\/wp-json\/wp\/v2\/faq_category?post=20632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}